{"id":22812,"date":"2026-03-09T04:02:42","date_gmt":"2026-03-09T04:02:42","guid":{"rendered":"https:\/\/www.southasiatraveljournal.com\/andaman-to-host-surfing-festival-this-april\/"},"modified":"2026-04-09T12:11:30","modified_gmt":"2026-04-09T12:11:30","slug":"andaman-acogera-un-festival-de-surf-este-mes-de-abril","status":"publish","type":"post","link":"https:\/\/www.southasiatraveljournal.com\/es\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\/","title":{"rendered":"Andam\u00e1n acoger\u00e1 un festival de surf este mes de abril"},"content":{"rendered":"<p>Las islas Andam\u00e1n y Nicobar cobrar\u00e1n vida con la cultura del surf, ya que Little Andaman acoger\u00e1 un festival de surf de cuatro d\u00edas, del 9 al 12 de abril, en la emblem\u00e1tica bah\u00eda de Butler. Organizado por el Departamento de Turismo de la Administraci\u00f3n de Andam\u00e1n y Nicobar, en colaboraci\u00f3n con la Federaci\u00f3n de Surf de la India, el evento celebra la aventura y la creciente identidad de las islas como destino de surf.<\/p>\n<p>El eje central del festival es el Little Andaman Pro 2026, la primera parada de la Serie Nacional de Surf y una prueba clasificatoria clave en el camino hacia el Campeonato Nacional. Con el respaldo de la Junta de Turismo de Andam\u00e1n y Nicobar, 60 atletas recibir\u00e1n apoyo total para el viaje desde Chennai, adem\u00e1s de alojamiento y comidas a partir del 6 de abril.<\/p>\n<p>M\u00e1s all\u00e1 de la competici\u00f3n, el festival ofrece una experiencia m\u00e1s amplia, desde la observaci\u00f3n de aves y el surf de remo hasta la observaci\u00f3n de las estrellas y la narraci\u00f3n de historias sobre el patrimonio, lo que lo convierte tanto en una celebraci\u00f3n de la riqueza natural y cultural de las islas como en un evento deportivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las islas Andam\u00e1n y Nicobar cobrar\u00e1n vida con la cultura del surf, ya que Little Andaman acoger\u00e1 un festival de surf de cuatro d\u00edas, del 9 al 12 de abril, en la emblem\u00e1tica bah\u00eda de Butler. Organizado por el Departamento de Turismo de la Administraci\u00f3n de Andam\u00e1n y Nicobar, en colaboraci\u00f3n con la Federaci\u00f3n de Surf de la India, el evento celebra la aventura y la creciente identidad de las islas como destino de surf. El eje central del festival es el Little Andaman Pro 2026, la primera parada de la Serie Nacional de Surf y una prueba clasificatoria clave<\/p>\n","protected":false},"author":1,"featured_media":21997,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[299],"tags":[],"class_list":["post-22812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-india-es"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Las islas Andam\u00e1n y Nicobar cobrar\u00e1n vida con la cultura del surf, ya que Little Andaman acoger\u00e1 un festival de surf de cuatro d\u00edas, del 9 al 12 de abril, en la emblem\u00e1tica bah\u00eda de Butler. Organizado por el Departamento de Turismo de la Administraci\u00f3n de Andam\u00e1n y Nicobar, en colaboraci\u00f3n con la Federaci\u00f3n de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Creative Travel Blogs\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.southasiatraveljournal.com\/es\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"The South Asia Travel Journal -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Andam\u00e1n acoger\u00e1 un festival de surf este mes de abril - The South Asia Travel Journal\" \/>\n\t\t<meta property=\"og:description\" content=\"Las islas Andam\u00e1n y Nicobar cobrar\u00e1n vida con la cultura del surf, ya que Little Andaman acoger\u00e1 un festival de surf de cuatro d\u00edas, del 9 al 12 de abril, en la emblem\u00e1tica bah\u00eda de Butler. Organizado por el Departamento de Turismo de la Administraci\u00f3n de Andam\u00e1n y Nicobar, en colaboraci\u00f3n con la Federaci\u00f3n de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.southasiatraveljournal.com\/es\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-03-09T04:02:42+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-04-09T12:11:30+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Andam\u00e1n acoger\u00e1 un festival de surf este mes de abril - The South Asia Travel Journal\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Las islas Andam\u00e1n y Nicobar cobrar\u00e1n vida con la cultura del surf, ya que Little Andaman acoger\u00e1 un festival de surf de cuatro d\u00edas, del 9 al 12 de abril, en la emblem\u00e1tica bah\u00eda de Butler. Organizado por el Departamento de Turismo de la Administraci\u00f3n de Andam\u00e1n y Nicobar, en colaboraci\u00f3n con la Federaci\u00f3n de\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\\\/#blogposting\",\"name\":\"Andam\\u00e1n acoger\\u00e1 un festival de surf este mes de abril - The South Asia Travel Journal\",\"headline\":\"Andam\\u00e1n acoger\\u00e1 un festival de surf este mes de abril\",\"author\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/author\\\/creativeblogs_admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Surfing-Canva.webp\",\"width\":1800,\"height\":800},\"datePublished\":\"2026-03-09T04:02:42+00:00\",\"dateModified\":\"2026-04-09T12:11:30+00:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\\\/#webpage\"},\"articleSection\":\"India, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/category\\\/india-es\\\/#listItem\",\"name\":\"India\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/category\\\/india-es\\\/#listItem\",\"position\":2,\"name\":\"India\",\"item\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/category\\\/india-es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\\\/#listItem\",\"name\":\"Andam\\u00e1n acoger\\u00e1 un festival de surf este mes de abril\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\\\/#listItem\",\"position\":3,\"name\":\"Andam\\u00e1n acoger\\u00e1 un festival de surf este mes de abril\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/category\\\/india-es\\\/#listItem\",\"name\":\"India\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/#organization\",\"name\":\"The South Asia Travel Journal\",\"url\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/author\\\/creativeblogs_admin\\\/#author\",\"url\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/author\\\/creativeblogs_admin\\\/\",\"name\":\"Creative Travel Blogs\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/creative-travel-co.jpg\",\"width\":96,\"height\":96,\"caption\":\"Creative Travel Blogs\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\\\/#webpage\",\"url\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\\\/\",\"name\":\"Andam\\u00e1n acoger\\u00e1 un festival de surf este mes de abril - The South Asia Travel Journal\",\"description\":\"Las islas Andam\\u00e1n y Nicobar cobrar\\u00e1n vida con la cultura del surf, ya que Little Andaman acoger\\u00e1 un festival de surf de cuatro d\\u00edas, del 9 al 12 de abril, en la emblem\\u00e1tica bah\\u00eda de Butler. Organizado por el Departamento de Turismo de la Administraci\\u00f3n de Andam\\u00e1n y Nicobar, en colaboraci\\u00f3n con la Federaci\\u00f3n de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/author\\\/creativeblogs_admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/author\\\/creativeblogs_admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Surfing-Canva.webp\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\\\/#mainImage\",\"width\":1800,\"height\":800},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\\\/#mainImage\"},\"datePublished\":\"2026-03-09T04:02:42+00:00\",\"dateModified\":\"2026-04-09T12:11:30+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/\",\"name\":\"The South Asia Travel Journal\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Andam\u00e1n acoger\u00e1 un festival de surf este mes de abril - The South Asia Travel Journal","description":"Las islas Andam\u00e1n y Nicobar cobrar\u00e1n vida con la cultura del surf, ya que Little Andaman acoger\u00e1 un festival de surf de cuatro d\u00edas, del 9 al 12 de abril, en la emblem\u00e1tica bah\u00eda de Butler. Organizado por el Departamento de Turismo de la Administraci\u00f3n de Andam\u00e1n y Nicobar, en colaboraci\u00f3n con la Federaci\u00f3n de","canonical_url":"https:\/\/www.southasiatraveljournal.com\/es\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.southasiatraveljournal.com\/es\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\/#blogposting","name":"Andam\u00e1n acoger\u00e1 un festival de surf este mes de abril - The South Asia Travel Journal","headline":"Andam\u00e1n acoger\u00e1 un festival de surf este mes de abril","author":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/author\/creativeblogs_admin\/#author"},"publisher":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.southasiatraveljournal.com\/wp-content\/uploads\/2026\/03\/Surfing-Canva.webp","width":1800,"height":800},"datePublished":"2026-03-09T04:02:42+00:00","dateModified":"2026-04-09T12:11:30+00:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\/#webpage"},"isPartOf":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\/#webpage"},"articleSection":"India, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/www.southasiatraveljournal.com\/es\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.southasiatraveljournal.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/www.southasiatraveljournal.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.southasiatraveljournal.com\/es\/category\/india-es\/#listItem","name":"India"}},{"@type":"ListItem","@id":"https:\/\/www.southasiatraveljournal.com\/es\/category\/india-es\/#listItem","position":2,"name":"India","item":"https:\/\/www.southasiatraveljournal.com\/es\/category\/india-es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.southasiatraveljournal.com\/es\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\/#listItem","name":"Andam\u00e1n acoger\u00e1 un festival de surf este mes de abril"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.southasiatraveljournal.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.southasiatraveljournal.com\/es\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\/#listItem","position":3,"name":"Andam\u00e1n acoger\u00e1 un festival de surf este mes de abril","previousItem":{"@type":"ListItem","@id":"https:\/\/www.southasiatraveljournal.com\/es\/category\/india-es\/#listItem","name":"India"}}]},{"@type":"Organization","@id":"https:\/\/www.southasiatraveljournal.com\/es\/#organization","name":"The South Asia Travel Journal","url":"https:\/\/www.southasiatraveljournal.com\/es\/"},{"@type":"Person","@id":"https:\/\/www.southasiatraveljournal.com\/es\/author\/creativeblogs_admin\/#author","url":"https:\/\/www.southasiatraveljournal.com\/es\/author\/creativeblogs_admin\/","name":"Creative Travel Blogs","image":{"@type":"ImageObject","@id":"https:\/\/www.southasiatraveljournal.com\/es\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\/#authorImage","url":"https:\/\/www.southasiatraveljournal.com\/wp-content\/uploads\/2024\/07\/creative-travel-co.jpg","width":96,"height":96,"caption":"Creative Travel Blogs"}},{"@type":"WebPage","@id":"https:\/\/www.southasiatraveljournal.com\/es\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\/#webpage","url":"https:\/\/www.southasiatraveljournal.com\/es\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\/","name":"Andam\u00e1n acoger\u00e1 un festival de surf este mes de abril - The South Asia Travel Journal","description":"Las islas Andam\u00e1n y Nicobar cobrar\u00e1n vida con la cultura del surf, ya que Little Andaman acoger\u00e1 un festival de surf de cuatro d\u00edas, del 9 al 12 de abril, en la emblem\u00e1tica bah\u00eda de Butler. Organizado por el Departamento de Turismo de la Administraci\u00f3n de Andam\u00e1n y Nicobar, en colaboraci\u00f3n con la Federaci\u00f3n de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\/#breadcrumblist"},"author":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/author\/creativeblogs_admin\/#author"},"creator":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/author\/creativeblogs_admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.southasiatraveljournal.com\/wp-content\/uploads\/2026\/03\/Surfing-Canva.webp","@id":"https:\/\/www.southasiatraveljournal.com\/es\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\/#mainImage","width":1800,"height":800},"primaryImageOfPage":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\/#mainImage"},"datePublished":"2026-03-09T04:02:42+00:00","dateModified":"2026-04-09T12:11:30+00:00"},{"@type":"WebSite","@id":"https:\/\/www.southasiatraveljournal.com\/es\/#website","url":"https:\/\/www.southasiatraveljournal.com\/es\/","name":"The South Asia Travel Journal","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"The South Asia Travel Journal -","og:type":"article","og:title":"Andam\u00e1n acoger\u00e1 un festival de surf este mes de abril - The South Asia Travel Journal","og:description":"Las islas Andam\u00e1n y Nicobar cobrar\u00e1n vida con la cultura del surf, ya que Little Andaman acoger\u00e1 un festival de surf de cuatro d\u00edas, del 9 al 12 de abril, en la emblem\u00e1tica bah\u00eda de Butler. Organizado por el Departamento de Turismo de la Administraci\u00f3n de Andam\u00e1n y Nicobar, en colaboraci\u00f3n con la Federaci\u00f3n de","og:url":"https:\/\/www.southasiatraveljournal.com\/es\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\/","article:published_time":"2026-03-09T04:02:42+00:00","article:modified_time":"2026-04-09T12:11:30+00:00","twitter:card":"summary_large_image","twitter:title":"Andam\u00e1n acoger\u00e1 un festival de surf este mes de abril - The South Asia Travel Journal","twitter:description":"Las islas Andam\u00e1n y Nicobar cobrar\u00e1n vida con la cultura del surf, ya que Little Andaman acoger\u00e1 un festival de surf de cuatro d\u00edas, del 9 al 12 de abril, en la emblem\u00e1tica bah\u00eda de Butler. Organizado por el Departamento de Turismo de la Administraci\u00f3n de Andam\u00e1n y Nicobar, en colaboraci\u00f3n con la Federaci\u00f3n de"},"aioseo_meta_data":{"post_id":"22812","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-04-09 12:11:30","updated":"2026-04-09 13:16:49","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.southasiatraveljournal.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.southasiatraveljournal.com\/es\/category\/india-es\/\" title=\"India\">India<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAndam\u00e1n acoger\u00e1 un festival de surf este mes de abril\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.southasiatraveljournal.com\/es\/"},{"label":"India","link":"https:\/\/www.southasiatraveljournal.com\/es\/category\/india-es\/"},{"label":"Andam\u00e1n acoger\u00e1 un festival de surf este mes de abril","link":"https:\/\/www.southasiatraveljournal.com\/es\/andaman-acogera-un-festival-de-surf-este-mes-de-abril\/"}],"featured_image_src":"https:\/\/www.southasiatraveljournal.com\/wp-content\/uploads\/2026\/03\/Surfing-Canva.webp","author_info":{"display_name":"Creative Travel Blogs","author_link":"https:\/\/www.southasiatraveljournal.com\/es\/author\/creativeblogs_admin\/"},"_links":{"self":[{"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/posts\/22812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/comments?post=22812"}],"version-history":[{"count":2,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/posts\/22812\/revisions"}],"predecessor-version":[{"id":22840,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/posts\/22812\/revisions\/22840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/media\/21997"}],"wp:attachment":[{"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/media?parent=22812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/categories?post=22812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/tags?post=22812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}