{"id":5247,"date":"2024-08-08T10:38:02","date_gmt":"2024-08-08T10:38:02","guid":{"rendered":"https:\/\/www.southasiatraveljournal.com\/?p=5247"},"modified":"2024-09-12T12:36:58","modified_gmt":"2024-09-12T12:36:58","slug":"salmon-con-costra-de-lentejas-con-dal-de-yogur-y-espinacas-y-chutney-de-albaricoque","status":"publish","type":"post","link":"https:\/\/www.southasiatraveljournal.com\/es\/salmon-con-costra-de-lentejas-con-dal-de-yogur-y-espinacas-y-chutney-de-albaricoque\/","title":{"rendered":"Salm\u00f3n con costra de lentejas con dal de yogur y espinacas, y chutney de albaricoque"},"content":{"rendered":"<p>RACIONES 2<\/p>\n<p>NUTRICI\u00d3N Aprox. 700 calor\u00edas<\/p>\n<p>Aqu\u00ed, estamos celebrando una de nuestras legumbres favoritas, us\u00e1ndola de dos maneras. Vamos a rebozar los filetes de salm\u00f3n con harina de lentejas. Un ligero espolvoreado de este ingrediente especial (simplemente lentejas finamente molidas) crea una corteza delicada con un sabor fuerte y tostado. Y como guarnici\u00f3n, vamos a usar lentejas enteras para hacer un dal cremoso, un guiso tradicional indio. Las nuestras son lentejas doradas de cocci\u00f3n r\u00e1pida, mezcladas con espinacas y yogur griego cremoso.<\/p>\n<p>&nbsp;<\/p>\n<p>Ingredientes<\/p>\n<ul>\n<li>2 filetes de salm\u00f3n<\/li>\n<li>\u00bd taza de lentejas doradas de cosecha<\/li>\n<li>\u2153 taza de albaricoques secos<\/li>\n<li>2 oz de espinacas<\/li>\n<li>1 manojo de cilantro<\/li>\n<li>\u00bd taza de yogur griego natural<\/li>\n<li><a href=\"https:\/\/www.blueapron.com\/recipes\/lentil-crusted-salmon-with-spinach-yogurt-dal-apricot-chutney\">2 cdas de ghee<\/a><\/li>\n<li>2 cdas de concentrado de tamarindo<\/li>\n<li>1 jengibre de 1 pulgada<\/li>\n<li>\u00bc taza de harina de lentejas<\/li>\n<li><a href=\"https:\/\/www.blueapron.com\/recipes\/lentil-crusted-salmon-with-spinach-yogurt-dal-apricot-chutney\">1 cda de chutney de albaricoque (curry de madras en polvo, semillas de comino, cardamomo molido, semillas de nigella, semillas de mostaza marr\u00f3n y pimienta de cayena)<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h4>Mezcla de especias para chutney de albaricoque<\/h4>\n<p>2 partes de curry de Madr\u00e1s en polvo<\/p>\n<p>2 partes de semillas de comino entero<\/p>\n<p>2 partes de cardamomo molido<\/p>\n<p>1 parte de semillas de Nigella enteras<\/p>\n<p>1 parte de semillas de mostaza marr\u00f3n enteras<\/p>\n<p>1 parte de pimienta de Cayena molida<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Preparar los ingredientes:<\/strong><\/p>\n<p>Lavar y secar los productos frescos. Retirar las hojas de cilantro de los tallos; desechar los tallos. Pelar y picar el jengibre. Cortar los albaricoques en dados peque\u00f1os.<\/p>\n<p><strong>Empezar el dal:<\/strong><\/p>\n<p>En una cacerola grande, calentar\u00a0<strong>la mitad del ghee\u00a0<\/strong>a temperatura media-alta hasta que se derrita. A\u00f1adir\u00a0<strong>la mitad del jengibre\u00a0<\/strong>y\u00a0<strong>la mitad de la mezcla de especias<\/strong>. Cocinar, removiendo frecuentemente, de 30 segundos a 1 minuto, o hasta que est\u00e9 fragante. A\u00f1adir las\u00a0<strong>lentejas\u00a0<\/strong>y\u00a0<strong>1\u00bd taza de agua<\/strong><strong>;\u00a0<\/strong>sazonar con sal y pimienta. Calentar a fuego alto hasta la ebullici\u00f3n. Una vez que hierva, reducir el fuego a medio y cocinar a fuego lento de 8 a 10 minutos, o hasta que las lentejas est\u00e9n tiernas y ligeramente desmenuzadas.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Hacer el chutney de albaricoque:<\/strong><\/p>\n<p>Mientras el dal se cocina, en una sart\u00e9n mediana (antiadherente, si la tiene), calentar el\u00a0<strong>ghee restante\u00a0<\/strong>a temperatura media-alta hasta que se derrita. A\u00f1adir la\u00a0<strong>mezcla restante de jengibre y especias<\/strong>. Cocinar, removiendo frecuentemente, de 2 a 3 minutos, o hasta que se ablanden y queden fragantes. A\u00f1adir los\u00a0<strong>albaricoques\u00a0<\/strong>y\u00a0<strong>\u00bd taza de agua;\u00a0<\/strong>sazonar con sal y pimienta. Cocinar, removiendo ocasionalmente, de 2 a 3 minutos, o hasta que la mayor parte del agua se haya evaporado. A\u00f1adir el\u00a0<strong>concentrado de tamarindo<\/strong>. Cocinar, removiendo frecuentemente, de 30 segundos a 1 minuto, o hasta que est\u00e9 bien mezclado. Retirar del fuego y echarlo en un reciipiente. Enjuagar y limpiar la sart\u00e9n.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Terminar el dal:<\/strong><\/p>\n<p>Remover las\u00a0<strong>espinacas\u00a0<\/strong>y el\u00a0<strong>yogur griego<\/strong>\u00a0en la cacerola del dal. Cocinar, removiendo constantemente, de 30 segundos a 1 minuto, o hasta que las espinacas est\u00e9n bien mezcladas y se hayan marchitado. Retirar del fuego, y sazonar con sal y pimienta al gusto. Deja apartado en un lugar c\u00e1lido.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Rebozar y cocinar el salm\u00f3n:<\/strong><\/p>\n<p>Secar los\u00a0<strong>filetes de salm\u00f3n\u00a0<\/strong>con toallas de papel; sazonar con sal y pimienta por ambos lados. Colocar la\u00a0<strong>harina de lentejas\u00a0<\/strong>en un plato. Rebozar cada filete con la harina de lentejas por ambos lados, sacudiendo el exceso. En la misma sart\u00e9n donde se ha hecho el chutney, calentar 2 cucharaditas de aceite de oliva a fuego medio-alto hasta que est\u00e9 caliente. A\u00f1adir los filetes rebozados y cocinar de 3 a 4 minutos por cada lado, o hasta que est\u00e9n dorados y cocidos al grado de cocci\u00f3n deseado. Retirar del fuego.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Emplatar:<\/strong><\/p>\n<p>Dividir el\u00a0<strong>dal terminado\u00a0<\/strong>y los\u00a0<strong>filetes de salm\u00f3n cocinados\u00a0<\/strong>entre dos platos. Adornar con el\u00a0<strong>cilantro<\/strong>. Servir con el\u00a0<strong>chutney de albaricoque<\/strong>\u00a0a un lado. \u00a1A disfrutar!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RACIONES 2 NUTRICI\u00d3N Aprox. 700 calor\u00edas Aqu\u00ed, estamos celebrando una de nuestras legumbres favoritas, us\u00e1ndola de dos maneras. Vamos a rebozar los filetes de salm\u00f3n con harina de lentejas. Un ligero espolvoreado de este ingrediente especial (simplemente lentejas finamente molidas) crea una corteza delicada con un sabor fuerte y tostado. Y como guarnici\u00f3n, vamos a usar lentejas enteras para hacer un dal cremoso, un guiso tradicional indio. Las nuestras son lentejas doradas de cocci\u00f3n r\u00e1pida, mezcladas con espinacas y yogur griego cremoso. &nbsp; Ingredientes 2 filetes de salm\u00f3n \u00bd taza de lentejas doradas de cosecha \u2153 taza de albaricoques secos<\/p>\n","protected":false},"author":1,"featured_media":4999,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[309],"tags":[],"class_list":["post-5247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas"],"aioseo_notices":[],"featured_image_src":"https:\/\/www.southasiatraveljournal.com\/wp-content\/uploads\/2024\/08\/Recipe_Blog.jpg","author_info":{"display_name":"Creative Travel Blogs","author_link":"https:\/\/www.southasiatraveljournal.com\/es\/author\/creativeblogs_admin\/"},"_links":{"self":[{"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/posts\/5247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/comments?post=5247"}],"version-history":[{"count":1,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/posts\/5247\/revisions"}],"predecessor-version":[{"id":5248,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/posts\/5247\/revisions\/5248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/media\/4999"}],"wp:attachment":[{"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/media?parent=5247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/categories?post=5247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/tags?post=5247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}