{"id":5257,"date":"2024-08-08T10:43:12","date_gmt":"2024-08-08T10:43:12","guid":{"rendered":"https:\/\/www.southasiatraveljournal.com\/?p=5257"},"modified":"2024-09-12T12:36:15","modified_gmt":"2024-09-12T12:36:15","slug":"goan-gambas-al-curry","status":"publish","type":"post","link":"https:\/\/www.southasiatraveljournal.com\/es\/goan-gambas-al-curry\/","title":{"rendered":"Goan Gambas al curry"},"content":{"rendered":"<p>Acerca de la receta de curry de gambas de Goan: Tambi\u00e9n conocido como Ambot Tik, el curry de gambas de Goan tiene langostinos cocinados en leche de coco con una salsa picante hecha de c\u00farcuma, pimienta negra, vinagre y coco. \u00a1Un plato cremoso y delicioso para saborear con todo tu coraz\u00f3n!<\/p>\n<p><strong>Ingredientes del curry de gambas de Goa<\/strong><\/p>\n<ul>\n<li>Langostinos de 500 gramos (sin c\u00e1scara y sin venas)<\/li>\n<li>1 cucharadita de c\u00farcuma<\/li>\n<li>al gusto de sal<\/li>\n<li>2 tazas de leche de coco<\/li>\n<li>200 gramos de cebollas picadas<\/li>\n<li>2 cucharadas de aceite<\/li>\n<li>2 chiles verdes masala<\/li>\n<li>4-5 chiles rojos enteros<\/li>\n<li>1 cucharadita de cilantro<\/li>\n<li>1 cucharadita de semillas de comino<\/li>\n<li>6 pimienta negra<\/li>\n<li>1\/2 cucharadita de c\u00farcuma<\/li>\n<li>1 jengibre<\/li>\n<li>6 clavos<\/li>\n<li>1\/2 taza de coco<\/li>\n<li>1\/4 taza de vinagre<\/li>\n<\/ul>\n<p><strong>C\u00f3mo hacer curry de gambas de cabra<\/strong><\/p>\n<p><strong>Preparar masala de gambas:<\/strong><\/p>\n<p>Moler todos los ingredientes con vinagre.<\/p>\n<p><strong>Prepara el curry:<\/strong><\/p>\n<ul>\n<li>Espolvorear las gambas con c\u00farcuma y sal. Mantener a un lado.<\/li>\n<li>Luego fre\u00edr las cebollas hasta que est\u00e9n ligeramente doradas.<\/li>\n<li>A\u00f1adir masala molida y fre\u00edr. Agregar las gambas y fre\u00edr hasta que est\u00e9n rosadas.<\/li>\n<li>Luego agregue un poco de leche de coco y hierva.<\/li>\n<li>Cocine a fuego lento durante 5 minutos y adorne con chiles verdes.<\/li>\n<\/ul>\n<p><strong>Ingredientes clave:<\/strong>\u00a0Langostinos (sin c\u00e1scara y sin vetas), C\u00farcuma, Sal, Leche de coco, Cebollas, Aceite, Chiles verdes masala, Chiles rojos enteros, Cilantro, Semillas de comino, Pimienta negra, C\u00farcuma, Jengibre, Clavo, Coco, Vinagre<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acerca de la receta de curry de gambas de Goan: Tambi\u00e9n conocido como Ambot Tik, el curry de gambas de Goan tiene langostinos cocinados en leche de coco con una salsa picante hecha de c\u00farcuma, pimienta negra, vinagre y coco. \u00a1Un plato cremoso y delicioso para saborear con todo tu coraz\u00f3n! Ingredientes del curry de gambas de Goa Langostinos de 500 gramos (sin c\u00e1scara y sin venas) 1 cucharadita de c\u00farcuma al gusto de sal 2 tazas de leche de coco 200 gramos de cebollas picadas 2 cucharadas de aceite 2 chiles verdes masala 4-5 chiles rojos enteros 1 cucharadita<\/p>\n","protected":false},"author":1,"featured_media":5085,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[309],"tags":[],"class_list":["post-5257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Acerca de la receta de curry de gambas de Goan: Tambi\u00e9n conocido como Ambot Tik, el curry de gambas de Goan tiene langostinos cocinados en leche de coco con una salsa picante hecha de c\u00farcuma, pimienta negra, vinagre y coco. \u00a1Un plato cremoso y delicioso para saborear con todo tu coraz\u00f3n! Ingredientes del curry de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Creative Travel Blogs\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.southasiatraveljournal.com\/es\/goan-gambas-al-curry\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"The South Asia Travel Journal -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Goan Gambas al curry - The South Asia Travel Journal\" \/>\n\t\t<meta property=\"og:description\" content=\"Acerca de la receta de curry de gambas de Goan: Tambi\u00e9n conocido como Ambot Tik, el curry de gambas de Goan tiene langostinos cocinados en leche de coco con una salsa picante hecha de c\u00farcuma, pimienta negra, vinagre y coco. \u00a1Un plato cremoso y delicioso para saborear con todo tu coraz\u00f3n! Ingredientes del curry de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.southasiatraveljournal.com\/es\/goan-gambas-al-curry\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-08-08T10:43:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-09-12T12:36:15+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Goan Gambas al curry - The South Asia Travel Journal\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Acerca de la receta de curry de gambas de Goan: Tambi\u00e9n conocido como Ambot Tik, el curry de gambas de Goan tiene langostinos cocinados en leche de coco con una salsa picante hecha de c\u00farcuma, pimienta negra, vinagre y coco. \u00a1Un plato cremoso y delicioso para saborear con todo tu coraz\u00f3n! Ingredientes del curry de\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/goan-gambas-al-curry\\\/#blogposting\",\"name\":\"Goan Gambas al curry - The South Asia Travel Journal\",\"headline\":\"Goan Gambas al curry\",\"author\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/author\\\/creativeblogs_admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Goan-Prawn-Curry-with-Coconut-Ambot-Tik-4-900x400-1.jpg\",\"width\":900,\"height\":400},\"datePublished\":\"2024-08-08T10:43:12+00:00\",\"dateModified\":\"2024-09-12T12:36:15+00:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/goan-gambas-al-curry\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/goan-gambas-al-curry\\\/#webpage\"},\"articleSection\":\"Recetas, Opcional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/goan-gambas-al-curry\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/category\\\/recetas\\\/#listItem\",\"name\":\"Recetas\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/category\\\/recetas\\\/#listItem\",\"position\":2,\"name\":\"Recetas\",\"item\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/category\\\/recetas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/goan-gambas-al-curry\\\/#listItem\",\"name\":\"Goan Gambas al curry\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/goan-gambas-al-curry\\\/#listItem\",\"position\":3,\"name\":\"Goan Gambas al curry\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/category\\\/recetas\\\/#listItem\",\"name\":\"Recetas\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/#organization\",\"name\":\"The South Asia Travel Journal\",\"url\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/author\\\/creativeblogs_admin\\\/#author\",\"url\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/author\\\/creativeblogs_admin\\\/\",\"name\":\"Creative Travel Blogs\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/goan-gambas-al-curry\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/creative-travel-co.jpg\",\"width\":96,\"height\":96,\"caption\":\"Creative Travel Blogs\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/goan-gambas-al-curry\\\/#webpage\",\"url\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/goan-gambas-al-curry\\\/\",\"name\":\"Goan Gambas al curry - The South Asia Travel Journal\",\"description\":\"Acerca de la receta de curry de gambas de Goan: Tambi\\u00e9n conocido como Ambot Tik, el curry de gambas de Goan tiene langostinos cocinados en leche de coco con una salsa picante hecha de c\\u00farcuma, pimienta negra, vinagre y coco. \\u00a1Un plato cremoso y delicioso para saborear con todo tu coraz\\u00f3n! Ingredientes del curry de\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/goan-gambas-al-curry\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/author\\\/creativeblogs_admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/author\\\/creativeblogs_admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Goan-Prawn-Curry-with-Coconut-Ambot-Tik-4-900x400-1.jpg\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/goan-gambas-al-curry\\\/#mainImage\",\"width\":900,\"height\":400},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/goan-gambas-al-curry\\\/#mainImage\"},\"datePublished\":\"2024-08-08T10:43:12+00:00\",\"dateModified\":\"2024-09-12T12:36:15+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/\",\"name\":\"The South Asia Travel Journal\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.southasiatraveljournal.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Goan Gambas al curry - The South Asia Travel Journal","description":"Acerca de la receta de curry de gambas de Goan: Tambi\u00e9n conocido como Ambot Tik, el curry de gambas de Goan tiene langostinos cocinados en leche de coco con una salsa picante hecha de c\u00farcuma, pimienta negra, vinagre y coco. \u00a1Un plato cremoso y delicioso para saborear con todo tu coraz\u00f3n! Ingredientes del curry de","canonical_url":"https:\/\/www.southasiatraveljournal.com\/es\/goan-gambas-al-curry\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.southasiatraveljournal.com\/es\/goan-gambas-al-curry\/#blogposting","name":"Goan Gambas al curry - The South Asia Travel Journal","headline":"Goan Gambas al curry","author":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/author\/creativeblogs_admin\/#author"},"publisher":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.southasiatraveljournal.com\/wp-content\/uploads\/2024\/08\/Goan-Prawn-Curry-with-Coconut-Ambot-Tik-4-900x400-1.jpg","width":900,"height":400},"datePublished":"2024-08-08T10:43:12+00:00","dateModified":"2024-09-12T12:36:15+00:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/goan-gambas-al-curry\/#webpage"},"isPartOf":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/goan-gambas-al-curry\/#webpage"},"articleSection":"Recetas, Opcional"},{"@type":"BreadcrumbList","@id":"https:\/\/www.southasiatraveljournal.com\/es\/goan-gambas-al-curry\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.southasiatraveljournal.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/www.southasiatraveljournal.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.southasiatraveljournal.com\/es\/category\/recetas\/#listItem","name":"Recetas"}},{"@type":"ListItem","@id":"https:\/\/www.southasiatraveljournal.com\/es\/category\/recetas\/#listItem","position":2,"name":"Recetas","item":"https:\/\/www.southasiatraveljournal.com\/es\/category\/recetas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.southasiatraveljournal.com\/es\/goan-gambas-al-curry\/#listItem","name":"Goan Gambas al curry"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.southasiatraveljournal.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.southasiatraveljournal.com\/es\/goan-gambas-al-curry\/#listItem","position":3,"name":"Goan Gambas al curry","previousItem":{"@type":"ListItem","@id":"https:\/\/www.southasiatraveljournal.com\/es\/category\/recetas\/#listItem","name":"Recetas"}}]},{"@type":"Organization","@id":"https:\/\/www.southasiatraveljournal.com\/es\/#organization","name":"The South Asia Travel Journal","url":"https:\/\/www.southasiatraveljournal.com\/es\/"},{"@type":"Person","@id":"https:\/\/www.southasiatraveljournal.com\/es\/author\/creativeblogs_admin\/#author","url":"https:\/\/www.southasiatraveljournal.com\/es\/author\/creativeblogs_admin\/","name":"Creative Travel Blogs","image":{"@type":"ImageObject","@id":"https:\/\/www.southasiatraveljournal.com\/es\/goan-gambas-al-curry\/#authorImage","url":"https:\/\/www.southasiatraveljournal.com\/wp-content\/uploads\/2024\/07\/creative-travel-co.jpg","width":96,"height":96,"caption":"Creative Travel Blogs"}},{"@type":"WebPage","@id":"https:\/\/www.southasiatraveljournal.com\/es\/goan-gambas-al-curry\/#webpage","url":"https:\/\/www.southasiatraveljournal.com\/es\/goan-gambas-al-curry\/","name":"Goan Gambas al curry - The South Asia Travel Journal","description":"Acerca de la receta de curry de gambas de Goan: Tambi\u00e9n conocido como Ambot Tik, el curry de gambas de Goan tiene langostinos cocinados en leche de coco con una salsa picante hecha de c\u00farcuma, pimienta negra, vinagre y coco. \u00a1Un plato cremoso y delicioso para saborear con todo tu coraz\u00f3n! Ingredientes del curry de","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/goan-gambas-al-curry\/#breadcrumblist"},"author":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/author\/creativeblogs_admin\/#author"},"creator":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/author\/creativeblogs_admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.southasiatraveljournal.com\/wp-content\/uploads\/2024\/08\/Goan-Prawn-Curry-with-Coconut-Ambot-Tik-4-900x400-1.jpg","@id":"https:\/\/www.southasiatraveljournal.com\/es\/goan-gambas-al-curry\/#mainImage","width":900,"height":400},"primaryImageOfPage":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/goan-gambas-al-curry\/#mainImage"},"datePublished":"2024-08-08T10:43:12+00:00","dateModified":"2024-09-12T12:36:15+00:00"},{"@type":"WebSite","@id":"https:\/\/www.southasiatraveljournal.com\/es\/#website","url":"https:\/\/www.southasiatraveljournal.com\/es\/","name":"The South Asia Travel Journal","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.southasiatraveljournal.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"The South Asia Travel Journal -","og:type":"article","og:title":"Goan Gambas al curry - The South Asia Travel Journal","og:description":"Acerca de la receta de curry de gambas de Goan: Tambi\u00e9n conocido como Ambot Tik, el curry de gambas de Goan tiene langostinos cocinados en leche de coco con una salsa picante hecha de c\u00farcuma, pimienta negra, vinagre y coco. \u00a1Un plato cremoso y delicioso para saborear con todo tu coraz\u00f3n! Ingredientes del curry de","og:url":"https:\/\/www.southasiatraveljournal.com\/es\/goan-gambas-al-curry\/","article:published_time":"2024-08-08T10:43:12+00:00","article:modified_time":"2024-09-12T12:36:15+00:00","twitter:card":"summary_large_image","twitter:title":"Goan Gambas al curry - The South Asia Travel Journal","twitter:description":"Acerca de la receta de curry de gambas de Goan: Tambi\u00e9n conocido como Ambot Tik, el curry de gambas de Goan tiene langostinos cocinados en leche de coco con una salsa picante hecha de c\u00farcuma, pimienta negra, vinagre y coco. \u00a1Un plato cremoso y delicioso para saborear con todo tu coraz\u00f3n! Ingredientes del curry de"},"aioseo_meta_data":{"post_id":"5257","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-08-08 10:43:12","updated":"2025-06-16 14:57:52","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.southasiatraveljournal.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.southasiatraveljournal.com\/es\/category\/recetas\/\" title=\"Recetas\">Recetas<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tGoan Gambas al curry\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.southasiatraveljournal.com\/es\/"},{"label":"Recetas","link":"https:\/\/www.southasiatraveljournal.com\/es\/category\/recetas\/"},{"label":"Goan Gambas al curry","link":"https:\/\/www.southasiatraveljournal.com\/es\/goan-gambas-al-curry\/"}],"featured_image_src":"https:\/\/www.southasiatraveljournal.com\/wp-content\/uploads\/2024\/08\/Goan-Prawn-Curry-with-Coconut-Ambot-Tik-4-900x400-1.jpg","author_info":{"display_name":"Creative Travel Blogs","author_link":"https:\/\/www.southasiatraveljournal.com\/es\/author\/creativeblogs_admin\/"},"_links":{"self":[{"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/posts\/5257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/comments?post=5257"}],"version-history":[{"count":1,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/posts\/5257\/revisions"}],"predecessor-version":[{"id":5258,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/posts\/5257\/revisions\/5258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/media\/5085"}],"wp:attachment":[{"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/media?parent=5257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/categories?post=5257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.southasiatraveljournal.com\/es\/wp-json\/wp\/v2\/tags?post=5257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}